{"id":23684,"date":"2026-07-15T13:40:25","date_gmt":"2026-07-15T11:40:25","guid":{"rendered":"https:\/\/bibliotecacomunaleacri.it\/?post_type=ajde_events&#038;p=23684"},"modified":"2026-07-15T13:40:25","modified_gmt":"2026-07-15T11:40:25","slug":"seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami","status":"publish","type":"ajde_events","link":"https:\/\/bibliotecacomunaleacri.it\/en\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/","title":{"rendered":"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Di Gino Mirocle Crisci    ore 17.30 <\/p>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"728\" height=\"1024\" src=\"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg\" alt=\"\" class=\"wp-image-23685\" srcset=\"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg 728w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-213x300.jpg 213w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-768x1080.jpg 768w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-1092x1536.jpg 1092w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-1457x2048.jpg 1457w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-9x12.jpg 9w, https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-scaled.jpg 1821w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><\/figure>","protected":false},"author":2,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"tags":[],"event_type":[],"event_type_2":[],"class_list":["post-23684","ajde_events","type-ajde_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bibliotecacomunaleacri.it\/en\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri\" \/>\n<meta property=\"og:description\" content=\"Di Gino Mirocle Crisci ore 17.30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bibliotecacomunaleacri.it\/en\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/\" \/>\n<meta property=\"og:site_name\" content=\"Biblioteca Comunale di Acri\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1821\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/\",\"url\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/\",\"name\":\"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg\",\"datePublished\":\"2026-07-15T11:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#website\",\"url\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/\",\"name\":\"Biblioteca Comunale di Acri\",\"description\":\"Vincenzo Padula\",\"publisher\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#organization\",\"name\":\"Biblioteca comunale di Acri - Vincenzo Padula\",\"url\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LOGOBIBLIONEWPADULA1.1.png\",\"contentUrl\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LOGOBIBLIONEWPADULA1.1.png\",\"width\":1437,\"height\":636,\"caption\":\"Biblioteca comunale di Acri - Vincenzo Padula\"},\"image\":{\"@id\":\"https:\\\/\\\/bibliotecacomunaleacri.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bibliotecacomunaleacri.it\/en\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/","og_locale":"en_GB","og_type":"article","og_title":"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri","og_description":"Di Gino Mirocle Crisci ore 17.30","og_url":"https:\/\/bibliotecacomunaleacri.it\/en\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/","og_site_name":"Biblioteca Comunale di Acri","og_image":[{"width":1821,"height":2560,"url":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/","url":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/","name":"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI - Biblioteca Comunale di Acri","isPartOf":{"@id":"https:\/\/bibliotecacomunaleacri.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/#primaryimage"},"image":{"@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/#primaryimage"},"thumbnailUrl":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg","datePublished":"2026-07-15T11:40:25+00:00","breadcrumb":{"@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/#primaryimage","url":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg","contentUrl":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2026\/07\/BIBLIOTECA-COMUNALE-SEMINARIO-CRISCI-728x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bibliotecacomunaleacri.it\/events\/seminario-la-fantastica-storia-della-geologia-calabrese-terremoti-e-tsunami\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bibliotecacomunaleacri.it\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/bibliotecacomunaleacri.it\/events\/"},{"@type":"ListItem","position":3,"name":"Seminario : LA FANTASTICA STORIA DELLA GEOLOGIA CALABRESE, TERREMOTI E TSUNAMI"}]},{"@type":"WebSite","@id":"https:\/\/bibliotecacomunaleacri.it\/#website","url":"https:\/\/bibliotecacomunaleacri.it\/","name":"Acre Municipal Library","description":"Vincenzo Padula","publisher":{"@id":"https:\/\/bibliotecacomunaleacri.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bibliotecacomunaleacri.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/bibliotecacomunaleacri.it\/#organization","name":"Biblioteca comunale di Acri - Vincenzo Padula","url":"https:\/\/bibliotecacomunaleacri.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bibliotecacomunaleacri.it\/#\/schema\/logo\/image\/","url":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2023\/09\/LOGOBIBLIONEWPADULA1.1.png","contentUrl":"https:\/\/bibliotecacomunaleacri.it\/wp-content\/uploads\/2023\/09\/LOGOBIBLIONEWPADULA1.1.png","width":1437,"height":636,"caption":"Biblioteca comunale di Acri - Vincenzo Padula"},"image":{"@id":"https:\/\/bibliotecacomunaleacri.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/ajde_events\/23684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/comments?post=23684"}],"wp:attachment":[{"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/media?parent=23684"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/tags?post=23684"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/event_type?post=23684"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/bibliotecacomunaleacri.it\/en\/wp-json\/wp\/v2\/event_type_2?post=23684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}